{"id":17573,"date":"2022-01-07T11:37:43","date_gmt":"2022-01-07T11:37:43","guid":{"rendered":"https:\/\/www.zazu-kids.com\/cody-le-crabe-projecteur-avec-vagues-en-mouvement-et-poissons-nageurs\/"},"modified":"2022-01-07T11:37:43","modified_gmt":"2022-01-07T11:37:43","slug":"cody-le-crabe-projecteur-avec-vagues-en-mouvement-et-poissons-nageurs","status":"publish","type":"post","link":"https:\/\/www.zazu-kids.com\/fr\/cody-le-crabe-projecteur-avec-vagues-en-mouvement-et-poissons-nageurs\/","title":{"rendered":"CODY LE CRABE &#8211; PROJECTEUR AVEC VAGUES EN MOUVEMENT ET POISSONS NAGEURS"},"content":{"rendered":"<p>Par Joyce, m\u00e8re, enseignante en \u00e9cole primaire et blogueuse invit\u00e9e de <a href=\"https:\/\/www.mamascrapelle.nl\/cody-de-krab-ocean-projector\/\"><em>Mama Scrapelle<\/em><\/a><\/p>\n<h4>&#8220;S&#8217;endormir plus vite avec Cody le crabe, un projecteur d&#8217;oc\u00e9an<\/h4>\n<p>Il y a des enfants qui ont du mal \u00e0 s&#8217;endormir. Il y a aussi des enfants qui se r\u00e9veillent assez souvent. Surtout pour les b\u00e9b\u00e9s et les jeunes enfants, ces nuits sans sommeil suffisant peuvent \u00eatre terribles. <a href=\"https:\/\/www.zazu-kids.com\/product\/cody\/\">Cody le crabe<\/a> de ZAZU peut venir \u00e0 la rescousse ! En tout cas, ce projecteur d&#8217;oc\u00e9an a aid\u00e9 ma fille (\u00e2g\u00e9e de deux ans) qui se r\u00e9veille souvent la nuit. Et Cody a \u00e9galement aid\u00e9 la fille de mon amie Ellen qui a tendance \u00e0 rester \u00e9veill\u00e9e pendant environ 30 minutes avant de s&#8217;endormir.&#8221;<br \/>\n&#8220;Transformez la chambre de votre enfant en un monde sous-marin plus vrai que nature.<br \/>\nLe projecteur de Cody montre des vagues en mouvement et des poissons qui nagent. La projection imite une mer bleue avec des poissons orange sur votre plafond, rien qu&#8217;en la regardant on se sent calme. M\u00eame mon mari s&#8217;est d\u00e9tendu en s&#8217;allongeant sur le canap\u00e9 et en regardant vers le plafond o\u00f9 se d\u00e9roulait un monde sous-marin r\u00e9aliste.<\/p>\n<h4>&#8220;Transformez la chambre de votre enfant en un monde sous-marin plus vrai que nature.<\/h4>\n<p>Le projecteur de Cody montre des vagues en mouvement et des poissons qui nagent. La projection imite une mer bleue avec des poissons orange sur votre plafond, rien qu&#8217;en la regardant on se sent calme. M\u00eame mon mari s&#8217;est d\u00e9tendu en s&#8217;allongeant sur le canap\u00e9 et en regardant vers le plafond o\u00f9 se d\u00e9roulait un monde sous-marin r\u00e9aliste.<\/p>\n<p>Outre la projection, Cody peut \u00e9galement diffuser trois m\u00e9lodies diff\u00e9rentes : des sons d&#8217;oc\u00e9an, des battements de c\u0153ur (parfaits pour les b\u00e9b\u00e9s !) et des berceuses. Vous pouvez s\u00e9lectionner la m\u00e9lodie et il y a aussi une option pour \u00e9teindre le son. Notre fils trouve le son de l&#8217;oc\u00e9an un peu tendu (il est tr\u00e8s sensible) et pr\u00e9f\u00e8re les berceuses. Alors que notre fille pr\u00e9f\u00e8re le son des battements de c\u0153ur.&#8221;<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Yz-Pec6Yntw\"><img decoding=\"async\" class=\"alignnone size-full wp-image-14161\" src=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-10_mamascrapelle.png\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" srcset=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-10_mamascrapelle.png 810w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-10_mamascrapelle-150x83.png 150w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-10_mamascrapelle-300x167.png 300w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-10_mamascrapelle-768x427.png 768w\" alt=\"Cody 10_mamascrapelle\" width=\"810\" height=\"450\" \/><\/a><\/p>\n<h4>&#8220;Le programme de sommeil en trois \u00e9tapes de Cody<\/h4>\n<p>Ce crabe a un programme de sommeil qui se compose de trois \u00e9tapes. Chaque \u00e9tape dure 10 minutes, donc au total 30 minutes jusqu&#8217;\u00e0 ce que le programme de sommeil s&#8217;arr\u00eate (et avec un peu de chance, votre petit est d\u00e9j\u00e0 endormi). Laissez-moi vous expliquer chaque \u00e9tape :<\/p>\n<p>1. Les 10 premi\u00e8res minutes sont destin\u00e9es \u00e0 calmer votre enfant. Vous verrez des vagues en mouvement, beaucoup de poissons nageant en orange et vous entendrez les sons relaxants de l&#8217;oc\u00e9an.<\/p>\n<p>2. Entre les minutes 10 et 20, la projection tente d&#8217;endormir votre enfant. Les vagues sont toujours en mouvement et les poissons nagent toujours, mais les poissons ont perdu leurs couleurs et, en g\u00e9n\u00e9ral, la projection est moins lumineuse. Les sons de l&#8217;oc\u00e9an ont \u00e9t\u00e9 remplac\u00e9s par des sons de bulles lents et hypnotisant.<\/p>\n<p>3. Les 10 derni\u00e8res minutes sont l\u00e0 pour donner le coup de pouce final et envoyer votre enfant au pays des r\u00eaves. Les vagues ne bougent plus, la luminosit\u00e9 est au plus bas et le son s&#8217;arr\u00eate au bout de 20 minutes. Il est bon de savoir que Cody s&#8217;\u00e9teint automatiquement apr\u00e8s 30 minutes.<\/p>\n<p>Les \u00e9tapes sont repr\u00e9sent\u00e9es dans l&#8217;image ci-dessous.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Yz-Pec6Yntw\"><img decoding=\"async\" class=\"alignnone wp-image-14155 size-full\" src=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/CODY_3-step-sleep-program-768x618.jpg\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" srcset=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/CODY_3-step-sleep-program-768x618.jpg 768w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/CODY_3-step-sleep-program-768x618-150x121.jpg 150w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/CODY_3-step-sleep-program-768x618-300x241.jpg 300w\" alt=\"CODY_3-step-sleep-program-768x618\" width=\"768\" height=\"618\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La fille de mon ami \u00e9tait tr\u00e8s triste lorsque Cody s&#8217;est arr\u00eat\u00e9 au bout de 30 minutes : Je n&#8217;ai vraiment pas touch\u00e9 le crabe mais il n&#8217;y a plus de projection ni de son&#8221;. Ma suggestion pour \u00e9viter une telle r\u00e9action de choc serait de dire \u00e0 votre enfant : &#8216;n&#8217;aie pas peur quand Cody s&#8217;\u00e9teint automatiquement, cela signifie que c&#8217;est vraiment l&#8217;heure de se coucher !'&#8221;.<\/p>\n<h4>&#8220;D\u00e9tecteur de pleurs<\/h4>\n<p>Personnellement, cette fonctionnalit\u00e9 me rend tr\u00e8s heureux. Lorsque votre enfant commence \u00e0 pleurer ou \u00e0 parler, Cody se rallume. Cela peut signifier que votre petit s&#8217;endort \u00e0 nouveau tout seul (cela arrive avec notre fille). D\u00e8s qu&#8217;elle commence \u00e0 r\u00e9clamer maman et\/ou papa, Cody se met en marche, elle s&#8217;arr\u00eate et se rendort un peu plus tard ! Si c&#8217;est quelque chose que vous ne voulez pas parce que vous pr\u00e9f\u00e9rez apaiser votre petit vous-m\u00eame, vous pouvez facilement d\u00e9sactiver le d\u00e9tecteur de pleurs.&#8221;<\/p>\n<p><a href=\"https:\/\/www.zazu-kids.com\/product\/cody\/\"><img decoding=\"async\" class=\"alignnone wp-image-14159\" src=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-7_mamascrapelle.jpeg\" sizes=\"(max-width: 508px) 85vw, 508px\" srcset=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-7_mamascrapelle.jpeg 1024w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-7_mamascrapelle-150x113.jpeg 150w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-7_mamascrapelle-300x225.jpeg 300w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-7_mamascrapelle-768x576.jpeg 768w\" alt=\"Cody 7_mamascrapelle\" width=\"508\" height=\"381\" \/><\/a><\/p>\n<h4>&#8220;Cody n&#8217;est pas seulement pour les b\u00e9b\u00e9s<\/h4>\n<p>Vous pouvez commencer \u00e0 utiliser ce crabe d\u00e8s la naissance de votre enfant. Ce sont surtout les parents de nouveau-n\u00e9s qui utilisent Cody. Cependant, je remarque que les enfants plus \u00e2g\u00e9s et m\u00eame les adultes appr\u00e9cient les fonctionnalit\u00e9s de Cody.<\/p>\n<p>Mon mari aime regarder les vagues en mouvement et les poissons qui nagent. Mon fils tr\u00e8s sensible (6 ans) est plus d\u00e9tendu lorsqu&#8217;il regarde des images qui bougent lentement au plafond. En cons\u00e9quence, il s&#8217;endort en ayant un meilleur \u00e9tat d&#8217;esprit. Ma fille et la fille d&#8217;Ellen appr\u00e9cient toutes deux Cody. Ma fille fait la grasse matin\u00e9e avec Cody et son amie dit : &#8220;Cody me fait m&#8217;endormir plus vite, la projection en mouvement est amusante \u00e0 regarder et les m\u00e9lodies sont relaxantes. Surtout les berceuses et les sons de l&#8217;oc\u00e9an ! Le son des battements de c\u0153ur n&#8217;arr\u00eatait pas de tourner dans ma t\u00eate et je l&#8217;ai donc moins aim\u00e9&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-14166\" title=\"Cody 1_mamascrapelle\" src=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-1_mamascrapelle.jpeg\" sizes=\"(max-width: 533px) 85vw, 533px\" srcset=\"https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-1_mamascrapelle.jpeg 1024w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-1_mamascrapelle-150x113.jpeg 150w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-1_mamascrapelle-300x225.jpeg 300w, https:\/\/www.zazu-kids.com\/wp-content\/uploads\/2020\/04\/Cody-1_mamascrapelle-768x576.jpeg 768w\" alt=\"Cody 1_mamascrapelle\" width=\"533\" height=\"401\" \/><\/p>\n<p>Love,<\/p>\n<p>Jocye<\/p>\n<p>\u00c9crit par Joyce. M\u00e8re de deux enfants, enseignante en \u00e9cole primaire et blogueuse invit\u00e9e sur \u00a0<a href=\"https:\/\/www.mamascrapelle.nl\/\">Mama Scrapelle<\/a><\/p>\n<p>Clause de non-responsabilit\u00e9 : Toutes les pens\u00e9es et opinions sont les miennes et ne sont pas influenc\u00e9es par ZAZU Kids.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Joyce, m\u00e8re, enseignante en \u00e9cole primaire et blogueuse invit\u00e9e de Mama Scrapelle &#8220;S&#8217;endormir plus vite avec Cody le crabe, un projecteur d&#8217;oc\u00e9an Il y a des enfants qui ont [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[411],"tags":[],"class_list":["post-17573","post","type-post","status-publish","format-standard","hentry","category-revue-de-produit"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/posts\/17573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/comments?post=17573"}],"version-history":[{"count":0,"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/posts\/17573\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/media?parent=17573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/categories?post=17573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zazu-kids.com\/fr\/wp-json\/wp\/v2\/tags?post=17573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}